{"id":148,"date":"2026-08-19T03:09:21","date_gmt":"2026-08-19T06:09:21","guid":{"rendered":"https:\/\/anpmat.org.br\/simposio-nacional-9\/?page_id=148"},"modified":"2026-08-19T03:16:20","modified_gmt":"2026-08-19T06:16:20","slug":"hospedagem","status":"publish","type":"page","link":"https:\/\/anpmat.org.br\/simposio-nacional-9\/hospedagem\/","title":{"rendered":"Hospedagem"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para facilitar a organiza\u00e7\u00e3o da sua estadia durante o <strong>9\u00ba Simp\u00f3sio Nacional da Forma\u00e7\u00e3o do Professor de Matem\u00e1tica<\/strong>, em <strong>S\u00e3o Lu\u00eds \u2013 MA<\/strong>, disponibilizamos abaixo sugest\u00f5es de hospedagem. As op\u00e7\u00f5es est\u00e3o divididas entre <strong>hot\u00e9is parceiros<\/strong>, que oferecem condi\u00e7\u00f5es especiais aos participantes do evento, e <strong>outras op\u00e7\u00f5es indicadas<\/strong>, sem v\u00ednculo comercial com a organiza\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Hot\u00e9is Parceiros (com desconto)<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Os hot\u00e9is abaixo firmaram parceria com a ANPMat e oferecem condi\u00e7\u00f5es diferenciadas aos participantes do Simp\u00f3sio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Soft Win &#8211; 10% de desconto com apresenta\u00e7\u00e3o do crach\u00e1 do evento<\/strong><\/p>\n\n\n<style>.kb-table-container148_73ffa0-a2{overflow-x:auto;}.kb-table-container .kb-table148_73ffa0-a2 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_73ffa0-a2 caption{text-align:center;}.kb-table-container .kb-table148_73ffa0-a2 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_73ffa0-a2 wp-block-kadence-table\"><table class=\"kb-table kb-table148_73ffa0-a2\">\n<tr class=\"kb-table-row kb-table-row148_823d22-1c\">\n<td  class=\"kb-table-data kb-table-data148_241ec5-0a\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_e8ceea-31\">\n\n<p class=\"wp-block-paragraph\">R. Fernando Cutrim, Quadra 21 &#8211; N\u00famero 04 &#8211; <strong>Ponta D&#8217;areia<\/strong>, S\u00e3o Lu\u00eds &#8211; MA, 65077-347<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_e8cbfc-eb\">\n<td  class=\"kb-table-data kb-table-data148_0e6bdc-23\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_134004-c2\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:reservas@softwinhotel.com.br\">reservas@softwinhotel.com.br<\/a>\u00a0<a href=\"mailto:vendas@softwinhotel.com.br\">vendas@softwinhotel.com.br<\/a>\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_d3fe03-64\">\n<td  class=\"kb-table-data kb-table-data148_69695e-ff\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_6fd16f-f1\">\n\n<p class=\"wp-block-paragraph\">98 4009-7676\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_b5e1c9-40\">\n<td  class=\"kb-table-data kb-table-data148_7109b9-fd\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_5e99ef-4e\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor (<strong>3.5<\/strong>\/5.0) &#8211; Booking (<strong>8.1<\/strong>\/10)<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_9a4abf-bd\">\n<td  class=\"kb-table-data kb-table-data148_a780da-e7\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_21ed3e-7f\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.softwinhotel.com.br\/\">https:\/\/www.softwinhotel.com.br\/<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Outras Op\u00e7\u00f5es Indicadas&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As op\u00e7\u00f5es a seguir s\u00e3o apenas sugest\u00f5es de localiza\u00e7\u00e3o e custo-benef\u00edcio em S\u00e3o Lu\u00eds, sem parceria comercial com o evento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Stop Way &#8211; N\u00e3o possui pacotes de desconto<\/strong><\/p>\n\n\n<style>.kb-table-container148_80be88-e8{overflow-x:auto;}.kb-table-container .kb-table148_80be88-e8 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_80be88-e8 caption{text-align:center;}.kb-table-container .kb-table148_80be88-e8 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_80be88-e8 wp-block-kadence-table\"><table class=\"kb-table kb-table148_80be88-e8\">\n<tr class=\"kb-table-row kb-table-row148_b726d7-49\">\n<td  class=\"kb-table-data kb-table-data148_3cb27d-ff\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_0f83ec-e3\">\n\n<p class=\"wp-block-paragraph\">Quadra 20, Lote 6 e 8 Rua 26 &#8211; <strong>Ponta D&#8217;areia<\/strong>, S\u00e3o Lu\u00eds &#8211; MA, 65077-640<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_641af0-71\">\n<td  class=\"kb-table-data kb-table-data148_00efc3-99\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_5724a7-7e\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:reservas@stopwayhotel.com.br\">reservas@stopwayhotel.com.br<\/a><\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_ffa716-26\">\n<td  class=\"kb-table-data kb-table-data148_2d6556-7e\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_df325c-ca\">\n\n<p class=\"wp-block-paragraph\">(98) 4009-7777 , \u00a0 (98) 98200-3636<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_376a75-54\">\n<td  class=\"kb-table-data kb-table-data148_77af47-91\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_f6513a-22\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor (<strong>4.0<\/strong>\/5.0) &#8211; Booking (<strong>8.7<\/strong>\/10)<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_f1a855-8c\">\n<td  class=\"kb-table-data kb-table-data148_7801eb-4b\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_8dc01e-f7\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.stopwayhotel.com.br\/\">https:\/\/www.stopwayhotel.com.br\/<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Abbeville<\/strong><\/p>\n\n\n<style>.kb-table-container148_6bc42e-90{overflow-x:auto;}.kb-table-container .kb-table148_6bc42e-90 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_6bc42e-90 caption{text-align:center;}.kb-table-container .kb-table148_6bc42e-90 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_6bc42e-90 wp-block-kadence-table\"><table class=\"kb-table kb-table148_6bc42e-90\">\n<tr class=\"kb-table-row kb-table-row148_c969b2-a3\">\n<td  class=\"kb-table-data kb-table-data148_2c87dc-24\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_d87784-db\">\n\n<p class=\"wp-block-paragraph\">Av. Castelo Branco, n\u00ba 500,<strong> Bairro S\u00e3o Francisco<\/strong>\u00a0 &#8211; S\u00e3o Lu\u00eds MA &#8211; CEP: 65076-090<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_22e255-fb\">\n<td  class=\"kb-table-data kb-table-data148_010edb-08\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_4df1f9-80\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:contato@hotelabbeville.com.br\">contato@hotelabbeville.com.br<\/a><\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_7d452a-21\">\n<td  class=\"kb-table-data kb-table-data148_5566f8-a7\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_98d44f-6f\">\n\n<p class=\"wp-block-paragraph\">Telefone +55 98 3217-3000Whatsapp (98) 3217-3000<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_8dafe4-4e\">\n<td  class=\"kb-table-data kb-table-data148_d3c709-d1\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_09320d-b3\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor (<strong>3.7<\/strong>\/5.0) &#8211; Booking <strong>(8.1<\/strong>\/10)<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_ab7166-d5\">\n<td  class=\"kb-table-data kb-table-data148_05a132-f2\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_eb901f-54\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/hotelabbeville.com.br\/\">https:\/\/hotelabbeville.com.br\/<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Hotel Premier<\/strong>&nbsp;<\/p>\n\n\n<style>.kb-table-container148_2778e3-25{overflow-x:auto;}.kb-table-container .kb-table148_2778e3-25 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_2778e3-25 caption{text-align:center;}.kb-table-container .kb-table148_2778e3-25 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_2778e3-25 wp-block-kadence-table\"><table class=\"kb-table kb-table148_2778e3-25\">\n<tr class=\"kb-table-row kb-table-row148_abcec8-4e\">\n<td  class=\"kb-table-data kb-table-data148_d82fc5-c4\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_9e9fd3-3a\">\n\n<p class=\"wp-block-paragraph\">Av. dos Holandeses \u00b7 n\u00famero 3 \u00b7 Ponta D\u2019areia \u00b7 S\u00e3o Lu\u00eds \u00b7 MA \u00b7 CEP 65075-650<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_d89996-ee\">\n<td  class=\"kb-table-data kb-table-data148_18c5ff-24\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_b69478-aa\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:reservas@hotelpremier.com.br\">reservas@hotelpremier.com.br<\/a><\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_6893c9-59\">\n<td  class=\"kb-table-data kb-table-data148_8c3514-aa\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_396808-e5\">\n\n<p class=\"wp-block-paragraph\">+55 98 3216-6666 &#8211; 98 9 99128-4894\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_2a64c0-5c\">\n<td  class=\"kb-table-data kb-table-data148_e40429-af\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_03891f-15\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor ( <strong>3.6<\/strong>\/5.0)<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_7cc080-50\">\n<td  class=\"kb-table-data kb-table-data148_eff72d-dc\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_dc5a93-3f\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/hotelpremier.com.br\/\">https:\/\/hotelpremier.com.br\/<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Rio Poty Hotel &amp; Resort&nbsp;<\/strong><\/p>\n\n\n<style>.kb-table-container148_603553-43{overflow-x:auto;}.kb-table-container .kb-table148_603553-43 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_603553-43 caption{text-align:center;}.kb-table-container .kb-table148_603553-43 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_603553-43 wp-block-kadence-table\"><table class=\"kb-table kb-table148_603553-43\">\n<tr class=\"kb-table-row kb-table-row148_109922-48\">\n<td  class=\"kb-table-data kb-table-data148_15d0d3-7a\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_078495-5a\">\n\n<p class=\"wp-block-paragraph\">Avenida dos Holandeses,<strong> Ponta D&#8217;Areia<\/strong> | S\u00e3o Lu\u00eds | Maranh\u00e3o | Brasil | CEP: 65077-357\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_e4ee63-3e\">\n<td  class=\"kb-table-data kb-table-data148_a1685f-61\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_472e91-c1\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:reservas@riopotysaoluis.com.br\">reservas@riopotysaoluis.com.br<\/a><\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_1d969a-44\">\n<td  class=\"kb-table-data kb-table-data148_edd31f-5d\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_d5fa1e-8a\">\n\n<p class=\"wp-block-paragraph\">Telefone: (98) 3015-4141Whatsapp: +55 (98) 9 8410-8155<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_a45d5f-11\">\n<td  class=\"kb-table-data kb-table-data148_8705ad-51\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_1dc345-d0\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor (<strong>3.5<\/strong>\/5.0) &#8211; Booking (<strong>7.9<\/strong>\/10)\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_8f9fbd-4f\">\n<td  class=\"kb-table-data kb-table-data148_8294b8-9e\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_9fd7c6-21\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.riopotysaoluis.com.br\/\">https:\/\/www.riopotysaoluis.com.br\/<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Ibis S\u00e3o Luis<\/strong><\/p>\n\n\n<style>.kb-table-container148_385fa8-53{overflow-x:auto;}.kb-table-container .kb-table148_385fa8-53 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_385fa8-53 caption{text-align:center;}.kb-table-container .kb-table148_385fa8-53 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_385fa8-53 wp-block-kadence-table\"><table class=\"kb-table kb-table148_385fa8-53\">\n<tr class=\"kb-table-row kb-table-row148_4ac109-18\">\n<td  class=\"kb-table-data kb-table-data148_25a593-11\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_d937a3-67\">\n\n<p class=\"wp-block-paragraph\">Av. Dos Holandeses 10 QD 11, Propriedade. S\u00e3o Marcos, <strong>Jardim Renascen\u00e7a<\/strong> 65075 650 SAO LUIS Brasil\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_7796c0-a8\">\n<td  class=\"kb-table-data kb-table-data148_ec616b-69\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_c3e137-30\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:H7200-RE@ACCOR.COM.BR\">H7200-RE@ACCOR.COM.BR<\/a>\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_b41b28-2b\">\n<td  class=\"kb-table-data kb-table-data148_f0326d-45\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_9a1453-c2\">\n\n<p class=\"wp-block-paragraph\">Telefone +55 98 3311-4060\u00a0Fax+55 98 3311-4070<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_fac10a-c4\">\n<td  class=\"kb-table-data kb-table-data148_ceed18-93\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_583b3f-ca\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor (<strong>3.9<\/strong>\/5.0) &#8211; Booking (<strong>7.7<\/strong>\/10)\u00a0<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_cbb48b-2d\">\n<td  class=\"kb-table-data kb-table-data148_18005f-84\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_73c2e3-6a\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/all.accor.com\/hotel\/7200\/index.pt.shtml\">https:\/\/all.accor.com\/hotel\/7200\/index.pt.shtml<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Veleiros Mar Hotel<\/strong><\/p>\n\n\n<style>.kb-table-container148_f37c62-d1{overflow-x:auto;}.kb-table-container .kb-table148_f37c62-d1 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table148_f37c62-d1 caption{text-align:center;}.kb-table-container .kb-table148_f37c62-d1 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}<\/style><div class=\"kb-table-container kb-table-container148_f37c62-d1 wp-block-kadence-table\"><table class=\"kb-table kb-table148_f37c62-d1\">\n<tr class=\"kb-table-row kb-table-row148_4988ff-0a\">\n<td  class=\"kb-table-data kb-table-data148_8cc5be-fc\">\n\n<p class=\"wp-block-paragraph\"><strong>Endere\u00e7o:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_3df91b-72\">\n\n<p class=\"wp-block-paragraph\">Av. dos Holandeses, Ponta D&#8217;Areia. S\u00e3o Lu\u00eds &#8211; Maranh\u00e3o &#8211; Brasil<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_363cb5-25\">\n<td  class=\"kb-table-data kb-table-data148_76ce8e-a9\">\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_3e3552-1b\">\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:reservas@veleiroshotel.com.br\">reservas@veleiroshotel.com.br<\/a><\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_5e347e-82\">\n<td  class=\"kb-table-data kb-table-data148_b96eec-e8\">\n\n<p class=\"wp-block-paragraph\"><strong>Telefones<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_0846ca-2a\">\n\n<p class=\"wp-block-paragraph\">(98) 2109-3000(98) 2109-3008<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_5de85f-37\">\n<td  class=\"kb-table-data kb-table-data148_8d43ac-4f\">\n\n<p class=\"wp-block-paragraph\"><strong>Avalia\u00e7\u00f5es<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_b38440-2b\">\n\n<p class=\"wp-block-paragraph\">Tripadvisor (<strong>3.1<\/strong>\/5.0) &#8211; Booking (<strong>7.7<\/strong>\/10)<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row148_d9c4e5-3b\">\n<td  class=\"kb-table-data kb-table-data148_c2c02d-0e\">\n\n<p class=\"wp-block-paragraph\"><strong>Site:<\/strong><\/p>\n\n<\/td>\n\n<td  class=\"kb-table-data kb-table-data148_1627e6-e9\">\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/veleiroshotel.com.br\/\">https:\/\/veleiroshotel.com.br\/<\/a><\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n\n<h4 class=\"wp-block-heading\"><strong>Informa\u00e7\u00f5es Importantes<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>As reservas devem ser feitas <strong>diretamente pelo participante<\/strong>, junto ao hotel escolhido.<\/li>\n\n\n\n<li>A organiza\u00e7\u00e3o do 9\u00ba Simp\u00f3sio Nacional da Forma\u00e7\u00e3o do Professor de Matem\u00e1tica <strong>n\u00e3o realiza reservas<\/strong> em nome dos participantes e <strong>n\u00e3o se responsabiliza<\/strong> por pre\u00e7os, disponibilidade, qualidade do servi\u00e7o, condi\u00e7\u00f5es de pagamento ou eventuais problemas relacionados \u00e0 hospedagem.<\/li>\n\n\n\n<li>As indica\u00e7\u00f5es acima t\u00eam car\u00e1ter <strong>meramente sugestivo<\/strong>, visando facilitar a busca por op\u00e7\u00f5es pr\u00f3ximas ao local do evento em S\u00e3o Lu\u00eds.<\/li>\n\n\n\n<li>Recomendamos que cada participante <strong>verifique diretamente com o hotel<\/strong> as condi\u00e7\u00f5es, pol\u00edticas de cancelamento e adequa\u00e7\u00e3o \u00e0s suas necessidades espec\u00edficas (acessibilidade, alimenta\u00e7\u00e3o, etc.) antes de efetuar a reserva.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Para facilitar a organiza\u00e7\u00e3o da sua estadia durante o 9\u00ba Simp\u00f3sio Nacional da Forma\u00e7\u00e3o do Professor de Matem\u00e1tica, em S\u00e3o Lu\u00eds \u2013 MA, disponibilizamos abaixo sugest\u00f5es de hospedagem. As op\u00e7\u00f5es est\u00e3o divididas entre hot\u00e9is parceiros, que oferecem condi\u00e7\u00f5es especiais aos participantes do evento, e outras op\u00e7\u00f5es indicadas, sem v\u00ednculo comercial com a organiza\u00e7\u00e3o. Hot\u00e9is Parceiros &#8230; <a title=\"Hospedagem\" class=\"read-more\" href=\"https:\/\/anpmat.org.br\/simposio-nacional-9\/hospedagem\/\" aria-label=\"Read more about Hospedagem\">Ler mais<\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-148","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/pages\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":2,"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/pages\/148\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/pages\/148\/revisions\/152"}],"wp:attachment":[{"href":"https:\/\/anpmat.org.br\/simposio-nacional-9\/wp-json\/wp\/v2\/media?parent=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}